{"id":46745,"date":"2026-09-01T16:16:21","date_gmt":"2026-09-01T14:16:21","guid":{"rendered":"https:\/\/hotelpartner.com\/de\/?p=46745"},"modified":"2026-08-31T16:19:39","modified_gmt":"2026-08-31T14:19:39","slug":"30-gop-als-ziel-warum-hotels-ihr-betriebsmodell-neu-denken-muessen-erklaert-urs-grimm-managing-partner-von-unisono-hospitality","status":"publish","type":"post","link":"https:\/\/hotelpartner.com\/de\/blog\/30-gop-als-ziel-warum-hotels-ihr-betriebsmodell-neu-denken-muessen-erklaert-urs-grimm-managing-partner-von-unisono-hospitality\/","title":{"rendered":"30 % GOP als Ziel: Warum Hotels ihr Betriebsmodell neu denken m\u00fcssen, erkl\u00e4rt Urs Grimm, Managing Partner von UNISONO Hospitality"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Wie k\u00f6nnen Hotels trotz massiv gestiegener Kosten nachhaltig profitabel wirtschaften? F\u00fcr <a href=\"https:\/\/www.linkedin.com\/in\/urs-grimm-143aba149\/\">Urs Grimm<\/a>, Co-Founder und Managing Partner bei UNISONO Hospitality, f\u00fchrt an einer grundlegenden Ver\u00e4nderung der Betriebsmodelle in Verbindung mit Prozess-Automatisierung kein Weg vorbei.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Denn w\u00e4hrend Betriebskosten gestiegen sind, stehen insbesondere kleinere und mittelst\u00e4ndische Hotels vor einem zus\u00e4tzlichen Problem: Viele Aufgaben m\u00fcssen heute mit immer weniger Fachkr\u00e4ften bew\u00e4ltigt werden. Gleichzeitig soll die Servicequalit\u00e4t nicht leiden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In der aktuellen Folge des Podcasts \u201eAUSGEBUCHT!\u201c spricht HotelPartner-CEO <a href=\"https:\/\/www.linkedin.com\/in\/oliver-meyer-ba7047148\/\">Oliver Meyer<\/a> mit Urs Grimm dar\u00fcber, wie Hoteliers diesen Spagat aufl\u00f6sen k\u00f6nnen. Seine These: <strong>Das Hotel der Zukunft muss sich st\u00e4rker auf das konzentrieren, was der Gast wirklich wahrnimmt \u2013 und Prozesse im Hintergrund konsequent automatisieren, digitalisieren oder auslagern.<\/strong> Dabei geht es nicht um Digitalisierung um ihrer selbst willen, sondern um ein neues Betriebsmodell.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jetzt die komplette Folge anh\u00f6ren:<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-spotify wp-block-embed-spotify wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Spotify Embed: Das klassische Hotelmodell hat ausgedient I Urs Grimm, Managing Partner @ UNISONO Hospitality #12\" style=\"border-radius: 12px\" width=\"624\" height=\"351\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\" src=\"https:\/\/open.spotify.com\/embed\/episode\/5RPzRMCtIbc1VpuUFUohAp\/video?utm_source=oembed\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"h-\"><\/p>\n\n\n\n<h2 id=\"h-warum-30-gop-fur-urs-grimm-die-entscheidende-marke-sind\" class=\"wp-block-heading\">Warum 30 % GOP f\u00fcr Urs Grimm die entscheidende Marke sind<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Im Gespr\u00e4ch verweist Urs Grimm darauf, dass der durchschnittliche Gross Operating Profit (GOP) vieler Drei- und Viersterne-Ferienhotels lediglich bei rund 17 bis 20 Prozent liegt. Aus seiner Sicht ist das langfristig nicht nachhaltig.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sein Zielbild ist deshalb klar: <strong>30 % GOP.<\/strong> Denn ein zu niedriger GOP l\u00e4sst kaum Spielraum f\u00fcr Miete, Abschreibungen, Investitionen oder eine nachhaltige Finanzierung. Gleichzeitig sinkt damit die Attraktivit\u00e4t eines Hotels f\u00fcr potenzielle Nachfolger oder Investoren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die entscheidende Frage lautet f\u00fcr Grimm deshalb nicht mehr nur: Wie k\u00f6nnen wir mehr Umsatz erzielen? Sondern: <strong>Welches Betriebsmodell erm\u00f6glicht es, gleichzeitig Gasterlebnis, Mitarbeitergesundheit und Profitabilit\u00e4t sicherzustellen?<\/strong><\/p>\n\n\n\n<h2 id=\"h-digitalisierung-allein-lost-das-kostenproblem-nicht\" class=\"wp-block-heading\">Digitalisierung allein l\u00f6st das Kostenproblem nicht<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Automatisierung und KI sind in aller Munde, doch genau hier sieht Urs Grimm eine der gr\u00f6\u00dften Gefahren: Hotels investieren in neue Technologie, behalten aber gleichzeitig ihre bisherigen Strukturen und Prozesse bei. Dann entsteht zwar eine moderne Systemlandschaft \u2013 aber keine echte Effizienz und erst recht keine Kosteneinsparung.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn beispielsweise eine Automatisierung eingef\u00fchrt wird, die Personalkosten am Ende aber nicht reduziert (werden k\u00f6nnen) und Mitarbeiter weiterhin dieselben Aufgaben erledigen wie zuvor, bleibt der wirtschaftliche Effekt aus.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seine Empfehlung lautet deshalb: <strong>Nicht mit der Software beginnen, sondern mit dem Ziel.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vor jeder Investition sollten Hoteliers zun\u00e4chst kl\u00e4ren:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Was soll durch Automatisierung und KI-Einsatz erreicht werden?<\/li>\n\n\n\n<li>Geht es prim\u00e4r um Kostensenkung oder soll mehr Zeit f\u00fcr den Gast entstehen?<\/li>\n\n\n\n<li>Welche Prozesse m\u00fcssen daf\u00fcr ver\u00e4ndert werden?<\/li>\n\n\n\n<li>Welche Rolle sollen Mitarbeiter k\u00fcnftig \u00fcbernehmen?<\/li>\n\n\n\n<li>Wie viel \u00fcberl\u00e4sst man dem Gast?<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Erst wenn diese Fragen beantwortet sind, sollten Betriebsmodell und Systemlandschaft entsprechend aufgebaut werden. F\u00fcr Urs Grimm steht dabei immer im Vordergrund, f\u00fcr den Gast mehr Aufenthaltsqualit\u00e4t zu schaffen und ihm jederzeit behilflich sein k\u00f6nnen, wenn er ein Problem hat.<\/p>\n\n\n\n<h2 id=\"h-automatisierung-macht-das-gasteerlebnis-nicht-unpersonlicher\" class=\"wp-block-heading\">Automatisierung macht das G\u00e4steerlebnis nicht unpers\u00f6nlicher<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Digitalisierung und Prozessautomatisierung wird h\u00e4ufig mit einem Verlust an pers\u00f6nlichem Service verbunden. Urs Grimm sieht genau das Gegenteil: Seine These ist, dass je mehr administrative Standardprozesse im Hintergrund automatisiert, digitalisiert oder ausgelagert werden, desto mehr Zeit bleibt den Mitarbeitern f\u00fcr den Gast.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Reservierungen, Distribution, Marketing oder andere Backoffice-Prozesse m\u00fcssen nicht zwingend vor Ort erledigt werden. Entscheidend ist, dass sie zuverl\u00e4ssig funktionieren; egal, ob aus einer Zentrale der Hotelgruppe heraus oder durch einen qualifizierten externen Dienstleister.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Mitarbeiter vor Ort soll und darf hingegen st\u00e4rker Gastgeber sein, ohne den Spagat zwischen E-Mail, Telefonat und gleichzeitigem G\u00e4stekontakt managen zu m\u00fcssen. Urs Grimm ist \u00fcberzeugt, diese Einsatzgebiete sind f\u00fcr Hotel-Kommunikationsfachleute (ein neuer Ausbildungsgang in der Schweiz) und andere junge Menschen \u00e4u\u00dferst attraktiv. Denn sie machen Unterschied zum Wettbewerb aus durch Empathie, pers\u00f6nliche Empfehlungen, Erlebnisse und echte Aufmerksamkeit.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Und das zahlt sich wiederum finanziell aus: Wenn Mitarbeiter weniger Zeit mit Administration verbringen, k\u00f6nnen sie sich intensiver auf anreisende G\u00e4ste vorbereiten, individuelle Bed\u00fcrfnisse erkennen und pers\u00f6nliche Empfehlungen f\u00fcr Upselling geben.<\/p>\n\n\n\n<h2 id=\"h-ki-agenten-als-nachste-stufe-der-automatisierung\" class=\"wp-block-heading\">KI-Agenten als n\u00e4chste Stufe der Automatisierung<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fcr Urs Grimm wird die Entwicklung noch weitergehen. W\u00e4hrend heute bereits viele Prozesse digitalisiert sind, k\u00f6nnten k\u00fcnftig KI-Agents zahlreiche administrative Aufgaben im Hintergrund \u00fcbernehmen und auch Insell\u00f6sungen miteinander verbinden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dazu geh\u00f6ren beispielsweise Kommissionsabrechnungen, OTA-Buchungskontrollen, Wholesaler-Kommunikation, Kreditkartenpr\u00fcfungen oder Teile des Debitorenmanagements, die in Zukunft von KI-Agenten \u00fcber mehrere Tools hinweg gesteuert und ausgef\u00fchrt werden. Dabei verschwindet der Mensch nicht vollst\u00e4ndig aus den Prozessen. Vielmehr \u00fcbernimmt er die Rolle des <strong>\u201eHuman in the Loop\u201c<\/strong>: Er \u00fcberwacht, steuert und greift dort ein, wo menschliche Expertise notwendig ist.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auch wenn KI-Agenten zumeist noch nicht zum Einsatz kommen, sieht Urs Grimm jedoch schon heute erste sinnvolle Quick Wins im Backoffice \u2013 beispielsweise bei der Organisation von E-Mail-Postf\u00e4chern, wiederverwendbaren Textbausteinen oder automatisierten Schnittstellen zwischen Inbox und PMS. Einfache Automatisierungen k\u00f6nnen mit Tools wie <strong>Make, N8N oder Lovable<\/strong> hergestellt werden.<\/p>\n\n\n\n<h2 id=\"h-das-fazit-erst-das-betriebsmodell-dann-die-technologie\" class=\"wp-block-heading\">Das Fazit: Erst das Betriebsmodell, dann die Technologie<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die Podcastfolge mit Urs Grimm zeigt eine These auf, die f\u00fcr viele Hotels entscheidend sein d\u00fcrfte: <strong>Digitalisierung allein spart noch keine Kosten. <\/strong>Wer lediglich bestehende Prozesse digitalisiert, ohne Rollen, Strukturen und Verantwortlichkeiten neu zu denken, riskiert hohe Investitionen ohne entsprechenden wirtschaftlichen Effekt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der bessere Ansatz beginnt deshalb mit diesen Fragen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Was soll mein Hotel f\u00fcr den Gast sein?<\/li>\n\n\n\n<li>Welche Prozesse muss ich daf\u00fcr selbst abbilden?<\/li>\n\n\n\n<li>Und welche Aufgaben k\u00f6nnen effizienter automatisiert oder ausgelagert werden?<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Erst daraus sollte sich die passende Automatisierung oder ggfs. Outsourcing-L\u00f6sung ergeben. Dann k\u00f6nnen die Mitarbeiter vor Ort wieder das tun, was ihnen und den G\u00e4sten Freude macht: Gastgeber sein. Und genau darin k\u00f6nnte einer der wichtigsten Hebel f\u00fcr die Profitabilit\u00e4t der Hotellerie liegen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>In der aktuellen Folge von \u201eAUSGEBUCHT!\u201c erfahren Sie au\u00dferdem:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>wie Outsourcing und Automatisierung die Teams vor Ort entlasten k\u00f6nnen<\/li>\n\n\n\n<li>warum sich die Rolle des Hotelmitarbeiters grundlegend ver\u00e4ndern wird<\/li>\n\n\n\n<li>und wie KI-Agents k\u00fcnftig zahlreiche Backoffice-Prozesse \u00fcbernehmen k\u00f6nnten<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/open.spotify.com\/episode\/5RPzRMCtIbc1VpuUFUohAp\">\ud83c\udfa7 <strong>Jetzt die komplette Folge von \u201eAUSGEBUCHT!\u201c anh\u00f6ren und erfahren, warum Profitabilit\u00e4t, Technologie und Gastfreundschaft kein Widerspruch sein m\u00fcssen.<\/strong><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wie k\u00f6nnen Hotels trotz massiv gestiegener Kosten nachhaltig profitabel wirtschaften? F\u00fcr Urs Grimm, Co-Founder und Managing Partner bei UNISONO Hospitality, f\u00fchrt an einer grundlegenden&hellip;<\/p>\n","protected":false},"author":7,"featured_media":46747,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","editor_notices":[],"footnotes":""},"categories":[1,195],"tags":[],"class_list":["post-46745","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemeines","category-podcast","entry"],"acf":[],"_links":{"self":[{"href":"https:\/\/hotelpartner.com\/de\/wp-json\/wp\/v2\/posts\/46745","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotelpartner.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hotelpartner.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hotelpartner.com\/de\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/hotelpartner.com\/de\/wp-json\/wp\/v2\/comments?post=46745"}],"version-history":[{"count":1,"href":"https:\/\/hotelpartner.com\/de\/wp-json\/wp\/v2\/posts\/46745\/revisions"}],"predecessor-version":[{"id":46749,"href":"https:\/\/hotelpartner.com\/de\/wp-json\/wp\/v2\/posts\/46745\/revisions\/46749"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hotelpartner.com\/de\/wp-json\/wp\/v2\/media\/46747"}],"wp:attachment":[{"href":"https:\/\/hotelpartner.com\/de\/wp-json\/wp\/v2\/media?parent=46745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotelpartner.com\/de\/wp-json\/wp\/v2\/categories?post=46745"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotelpartner.com\/de\/wp-json\/wp\/v2\/tags?post=46745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}